{"id":1313,"date":"2024-05-06T04:27:59","date_gmt":"2024-05-06T04:27:59","guid":{"rendered":"https:\/\/lari.themesawesome.com\/ressources\/"},"modified":"2025-07-31T11:38:13","modified_gmt":"2025-07-31T11:38:13","slug":"ressources","status":"publish","type":"page","link":"https:\/\/lari.lu\/fr\/ressources\/","title":{"rendered":"Ressources"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1313\" class=\"elementor elementor-1313 elementor-383\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c58c70d e-con-full e-flex e-con e-parent\" data-id=\"c58c70d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-74a069a e-con-full hero-col-1 e-flex e-con e-child\" data-id=\"74a069a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b3c959 title-hero2 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7b3c959\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Ressources<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bdea5e8 e-con-full e-flex elementor-invisible e-con e-parent\" data-id=\"bdea5e8\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5b3ef0c e-con-full e-flex e-con e-child\" data-id=\"5b3ef0c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fdd34a3 elementor-widget elementor-widget-spacer\" data-id=\"fdd34a3\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-408e034 e-con-full e-flex e-con e-parent\" data-id=\"408e034\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f5c9b6 elementor-widget__width-inherit elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"0f5c9b6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Sur cette page, vous trouverez un ensemble de ressources qui vous aideront \u00e0 mieux comprendre l&rsquo;int\u00e9grit\u00e9 de la recherche et la conduite responsable de la recherche en g\u00e9n\u00e9ral, et les activit\u00e9s de la LARI en particulier.<br \/>L&rsquo;aper\u00e7u comprend des liens vers des codes de conduite, des lignes directrices et des recommandations sur la mani\u00e8re de mener des recherches de mani\u00e8re responsable et int\u00e8gre, ainsi que des liens vers des plateformes et des projets qui traitent de l&rsquo;int\u00e9grit\u00e9 de la recherche, de l&rsquo;\u00e9thique de la recherche, de la recherche et de l&rsquo;innovation responsables, de la science ouverte et de l&rsquo;\u00e9valuation de la recherche. \u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-409146f e-con-full e-flex e-con e-parent\" data-id=\"409146f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e471386 main-title elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e471386\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Liens utiles<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b93afc e-con-full e-flex e-con e-parent\" data-id=\"5b93afc\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1f6858 elementor-widget elementor-widget-lari-link-loop-2\" data-id=\"c1f6858\" data-element_type=\"widget\" data-widget_type=\"lari-link-loop-2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\n\t.lari-link-loop-2 .link-item:first-child {\n        border-top: 1px solid #000000;\n\t}\n    .lari-link-loop-2 .link-item {\n        justify-content: space-between;\n        align-items: center;\n        border-bottom: 1px solid #000000;\n        padding: 20px 32.5px;\n        display: none;\n    }\n    .lari-link-loop-2 .link-item .link-title{\n        width: 40%;\n        display: flex;\n    }\n    .lari-link-loop-2 .link-cat {\n        width: 20%;\n        display: flex;\n        justify-content: center;\n    }\n    .lari-link-loop-2 .link-cat-mobile {\n        display: none;\n    }\n    .lari-link-loop-2 .link-url {\n        width: 40%;\n        display: flex;\n        justify-content: flex-end;\n    }\n    \n    \/* .lari-link-loop-2 .link-item:first-child {\n        border-top: 1px solid #000;\n    } *\/\n    .lari-link-loop-2 .link-item p {\n        margin: 0;\n    }\n    .lari-link-loop-2 .link-item a {\n        display: inline-flex;\n        align-items: center;\n        gap: 8px;\n        font-family: Neue Haas Grotesk Display Pro;\n        font-size: 16px;\n        font-weight: 500;\n        letter-spacing: 0.01em;\n        color: #000000;\n        border-bottom: 1px solid #000;\n    }\n\n    .lari-link-loop-2 .link-wrap{\n        margin-bottom: 40px;\n    }\n\n    .lari-link-loop-2 .link-wrap .link-filter-wrap{\n        display: flex;\n        gap: 48px;\n        margin-bottom: 100px;\n\t\tpadding-left: 32.5px;\n    }\n\n    .lari-link-loop-2 .link-wrap .items{\n        margin-bottom: 36px;\n    }\n\n    .lari-link-loop-2 .link-wrap .link-filter-wrap .button-filter{\n        cursor: pointer;\n    }\n\n    .lari-link-loop-2 .load-more{\n        color: #fff;\n        display: flex;\n        align-items: center;\n        justify-content: center;\n        padding: 16px;\n        gap: 16px;\n        background-color: #D5433B;\n        border-radius: 32px;\n        width: max-content;\n        border: 1px solid black;\n\t\tmargin-left: 32.5px;\n    }\n\n    @media only screen and (max-width: 768px) {\n\t\t.lari-link-loop-2 .link-item {\n\t\t\tpadding: 20px 16px;\n\t\t}\n\t\t.lari-link-loop-2 .load-more {\n\t\t\tmargin-left: 16px;\n\t\t}\n        .lari-link-loop-2 .link-item .link-title {\n            width: 45%;\n        }\n\n        .lari-link-loop-2 .link-wrap .link-filter-wrap{\n            display: none;\n        }\n\n        .lari-link-loop-2 .link-item{\n            flex-direction: column;\n            align-items: flex-start;\n            justify-content: flex-start;\n            gap: 10px;\n        }\n\n        .lari-link-loop-2 .link-item .link-title{\n            width: unset;\n        }\n\n        .lari-link-loop-2 .link-cat{\n            width: unset;\n            font-weight: bold;\n            display: none;\n        }\n\n        .lari-link-loop-2 .link-url{\n            width: unset;\n        }\n\n        .lari-link-loop-2 .link-cat-mobile {\n            color: #D5433B;\n            display: block;\n        }\n    }\n\n    \n<\/style>\n\n\n\n<div class=\"lari-link-loop-2\">\n    <div class=\"link-wrap\">\n        <div class=\"link-filter-wrap\">\n            <span>Filter by:<\/span>\n            <span class=\"button-filter\" data-filter=\"all\">All<\/span>\n                    <\/div>\n        <div class=\"items\">\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>European Network of Research Integrity Offices (ENRIO)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.enrio.eu\/\">https:\/\/www.enrio.eu\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>European Network of Research Ethics and Research Integrity (ENERI)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/eneri.eu\">https:\/\/eneri.eu                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>European Network of Research Ethics Committees (EUREC)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/eurecnet.eu\">https:\/\/eurecnet.eu                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>European Network for Academic Integrity (ENAI)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/academicintegrity.eu\">https:\/\/academicintegrity.eu                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>World Conferences on Research Integrity<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.wcrif.org\/\">https:\/\/www.wcrif.org\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>The Embassy of Good Science<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/embassy.science\">https:\/\/embassy.science                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>ENERI Classroom<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/classroom.eneri.eu\/\">https:\/\/classroom.eneri.eu\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Committee on Publication Ethics (COPE)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/publicationethics.org\/\">https:\/\/publicationethics.org\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>RRI Tools<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/rri-tools.eu\/\">https:\/\/rri-tools.eu\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Comit\u00e9 National d&#039;Ethique de Recherche (CNER)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/cner.gouvernement.lu\/fr.html\">https:\/\/cner.gouvernement.lu\/fr.html                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>European Group on Ethics in Science and New Technologies (EGE)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/research-and-innovation.ec.europa.eu\/strategy\/support-policy-making\/scientific-support-eu-policies\/european-group-ethics_en\">https:\/\/research-and-innovation.ec.europa.eu\/strategy\/support-policy-making\/scientific-support-eu-policies\/european-group-ethics_en                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Council of Europe Platform on Ethics, Transparency and Integrity in Education (ETINED)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.coe.int\/en\/web\/ethics-transparency-integrity-in-education\">https:\/\/www.coe.int\/en\/web\/ethics-transparency-integrity-in-education                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>GO FAIR<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.go-fair.org\/\">https:\/\/www.go-fair.org\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>OpenAIRE<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.openaire.eu\/\">https:\/\/www.openaire.eu\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Institut de Recherche et d\u2019Action sur la Fraude et le Plagiat Acad\u00e9miques (IRAFPA)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/irafpa.org\/\">https:\/\/irafpa.org\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Office of Research Integrity (USA)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/ori.hhs.gov\/\">https:\/\/ori.hhs.gov\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Rotterdam Dilemma Game<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.eur.nl\/en\/about-eur\/policy-and-regulations\/integrity\/research-integrity\/dilemma-game\">https:\/\/www.eur.nl\/en\/about-eur\/policy-and-regulations\/integrity\/research-integrity\/dilemma-game                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>European Code of Conduct for Research Integrity<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/allea.org\/portfolio-item\/european-code-of-conduct-2023\/\">https:\/\/allea.org\/portfolio-item\/european-code-of-conduct-2023\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Global Code of Conduct for Equitable Research Partnerships<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.globalcodeofconduct.org\/\">https:\/\/www.globalcodeofconduct.org\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>ICMJE Guidelines on Authorship (Vancouver Recommendations)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.icmje.org\/recommendations\/browse\/roles-and-responsibilities\/defining-the-role-of-authors-and-contributors.html\">https:\/\/www.icmje.org\/recommendations\/browse\/roles-and-responsibilities\/defining-the-role-of-authors-and-contributors.html                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>CARE Principles for Indigenous Data Governance<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.gida-global.org\/care\">https:\/\/www.gida-global.org\/care                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Website\">\n                <div class=\"link-cat-mobile\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Coalition for Advancing Research Assessment (CoARA)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Website<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/coara.eu\/\">https:\/\/coara.eu\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Agreement on Reforming Research Assessment (CoARA)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/coara.eu\/agreement\/the-agreement-full-text\/\">https:\/\/coara.eu\/agreement\/the-agreement-full-text\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Declaration on Research Assessment (DORA)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/sfdora.org\/\">https:\/\/sfdora.org\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Singapore Statement on Research Integrity<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.wcrif.org\/guidance\/singapore-statement\">https:\/\/www.wcrif.org\/guidance\/singapore-statement                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Montreal Statement on Research Integrity in Cross-Boundary Research Collaborations<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.wcrif.org\/guidance\/montreal-statement\">https:\/\/www.wcrif.org\/guidance\/montreal-statement                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Amsterdam Agenda on Research Integrity<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.wcrif.org\/guidance\/amsterdam-agenda\">https:\/\/www.wcrif.org\/guidance\/amsterdam-agenda                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Hong Kong Principles for Assessing Researchers<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.wcrif.org\/guidance\/hong-kong-principles\">https:\/\/www.wcrif.org\/guidance\/hong-kong-principles                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>The Cape Town Statement on Fostering Research Integrity through Fairness and Equity<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.wcrif.org\/guidance\/cape-town-statement\">https:\/\/www.wcrif.org\/guidance\/cape-town-statement                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>ROSiE General Guidelines on Responsible Open Science<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/zenodo.org\/records\/10046520\">https:\/\/zenodo.org\/records\/10046520                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Barcelona Declaration on Open Research Information<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/barcelona-declaration.org\/\">https:\/\/barcelona-declaration.org\/                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Guideline\">\n                <div class=\"link-cat-mobile\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Guide for Research Ethics Committee Members (Council of Europe)<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Guideline<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.coe.int\/en\/web\/bioethics\/guide-for-research-ethics-committees-members\">https:\/\/www.coe.int\/en\/web\/bioethics\/guide-for-research-ethics-committees-members                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Report\">\n                <div class=\"link-cat-mobile\">\n                    <span>Report<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>The Belmont Report<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Report<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.hhs.gov\/ohrp\/regul...\">https:\/\/www.hhs.gov\/ohrp\/regul...                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Video\">\n                <div class=\"link-cat-mobile\">\n                    <span>Video<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>Top 10 Tips for Robust &amp; Ethical Research<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Video<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.youtube.com\/watch...\">https:\/\/www.youtube.com\/watch...                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                        <div class=\"link-item link-item2 all Video\">\n                <div class=\"link-cat-mobile\">\n                    <span>Video<\/span>\n                <\/div>\n                <div class=\"link-title\">\n                    <p>The Ethical Path to Authorship<\/p>\n                <\/div>\n                <div class=\"link-cat\">\n                    <span>Video<\/span>\n                <\/div>\n                <div class=\"link-url\">\n                    <a href=\"https:\/\/www.youtube.com\/watch...\">https:\/\/www.youtube.com\/watch...                        <svg width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"><\/circle>\n                            <path d=\"M10.8285 9.4142L10.8285 5.17156M10.8285 5.17156L6.58583 5.17156M10.8285 5.17156L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <a href=\"#\" data-filter=\"all\" class=\"load-more\" style=\"display: none;\" id=\"loadMore\">\n        Load More\n        <svg width=\"18\" height=\"19\" viewBox=\"0 0 18 19\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n        <circle cx=\"9\" cy=\"9.5\" r=\"8.5\" transform=\"rotate(-90 9 9.5)\" fill=\"white\" stroke=\"black\"\/>\n        <path d=\"M10 12.5L13 9.5M13 9.5L10 6.5M13 9.5H5\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n        <\/svg>\n    <\/a>\n<\/div>\n\n<script>\n    (function($) {\n        'use strict';\n\n        $(document).ready(function() {\n            $('.link-filter-wrap .button-filter').on('click', function() {\n                var filterValue = $(this).attr('data-filter');\n\n                if (filterValue == 'all') {\n                    $('.items .link-item2').show();\n                } else {\n                    $('.items .link-item2').hide();\n                    $('.items .link-item2.' + filterValue).show();\n                }\n\n                $(\".link-item2\").css('display', 'none')\n                $(\"#loadMore\").hide();\n\n                $(\".link-item2.\"+$(this).attr('data-filter')).slice(0, 6).css('display', 'flex');\n                if ($(\".link-item2.\"+$(this).attr('data-filter')+\":hidden\").length != 0) {\n                    $(\"#loadMore\").show();\n                }\n\n                $('.load-more').attr('data-filter', filterValue)\n\n                \/\/ Add active class to the clicked button\n                $('.link-filter-wrap .button-filter').removeClass('active');\n                $(this).addClass('active');\n            });\n\n            $(\".link-item2\").slice(0, 6).css('display', 'flex');\n            if ($(\".link-item2:hidden\").length != 0) {\n                $(\"#loadMore\").show();\n            }\n\n            $(\"#loadMore\").on(\"click\", function(e) {\n                e.preventDefault();\n                var filterValue = $(this).attr('data-filter');\n                if(filterValue == 'all'){\n                    $(\".link-item2:hidden\")\n                        .slice(0, 6) \/\/ select next hidden 2 & show them\n                        .slideDown()\n                        .css('display', 'flex');\n                    if ($(\".link-item2:hidden\").length == 0) { \/\/ check if any hidden divs still exist\n                        $(\"#loadMore\").fadeOut(\"slow\");\n                    }\n                }else{\n                    $(\".link-item2.\"+filterValue+\":hidden\")\n                        .slice(0, 6) \/\/ select next hidden 2 & show them\n                        .slideDown()\n                        .css('display', 'flex');\n                    if ($(\".link-item2.\"+filterValue+\":hidden\").length == 0) { \/\/ check if any hidden divs still exist\n                        $(\"#loadMore\").fadeOut(\"slow\");\n                    }\n                }\n            });\n\n\n        });\n    })(jQuery);\n<\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c13d263 e-con-full e-flex e-con e-parent\" data-id=\"c13d263\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc166d9 main-title elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"dc166d9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eef0f49 elementor-widget elementor-widget-lari-faq-loop\" data-id=\"eef0f49\" data-element_type=\"widget\" data-widget_type=\"lari-faq-loop.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\n    .lari-faq-block {\n        display: flex;\n        flex-wrap: wrap;\n        flex-direction: column;\n        position: relative;\n    }\n    .lari-faq-loop {\n        display: grid;\n        grid-template-columns: repeat(2, minmax(0, 1fr));\n        column-gap: 20px;\n    }\n    .lari-faq-loop.loading {\n        opacity: 0.5;\n    }\n    .lari-faq-item {\n        margin-bottom: 20px;\n        box-sizing: border-box;\n    }\n    .lari-faq-item.right {\n        float: right;\n    }\n    .faq-title {\n        display: flex;\n        padding: 10px 10px;\n        background-color: rgba(82, 159, 220, 0.10);\n        align-items: center;\n        cursor: pointer;\n    }\n    .faq-title h3 {\n        font-size: 16px;\n        line-height: 1;\n        font-weight: 700;\n        color: #000000;\n        flex: 1;\n        margin: 0;\n    }\n    .faq-title .faq-icon {\n        display: flex;\n        width: 16px;\n        height: 16px;\n        align-items: center;\n        justify-content: center;\n        border-radius: 50%;\n        background-color: #c0ddf3;\n    }\n    .faq-title .faq-icon svg {\n        transform: rotate(180deg);\n        -webkit-transform: rotate(180deg);\n        transition: all 0.3s ease;\n    }\n    .lari-faq-item.faq-show .faq-title .faq-icon svg {\n        transform: rotate(0deg);\n        -webkit-transform: rotate(0deg);\n        transition: all 0.3s ease;\n    }\n    .faq-details {\n        display: none;\n        margin-top: 10px;\n        background-color: #ffffff;\n    }\n    .faq-details {\n        font-size: 16px;\n        line-height: 1.2;\n        color: #000000;\n        margin: 0;\n    }\n    .lari-faq-block .lari-faq-load {\n        display: flex;\n        align-items: center;\n        justify-content: center;\n        padding: 16px 16px;\n        border: 1px solid #000000;\n        color: #ffffff;\n        background-color: #D5433B;\n        border-radius: 50px;\n        column-gap: 20px;\n        font-size: 16px;\n    }\n    .lari-faq-load svg {\n        width: 18px;\n        min-width: 18px;\n        height: 18px;\n    }\n    .lari-faq-loop #infscr-loading {\n        position: absolute;\n        top: 100%;\n        left: 50%;\n        text-align: center;\n        transform: translateX(-50%);\n        -webkit-transform: translateX(-50%);\n    }\n    .lari-faq-loop #infscr-loading img {\n        width: 70px;\n        height: 70px;\n    }\n    .lari-faq-not-found {\n        display: none;\n        text-align: center;\n    }\n    .lari-faq-not-found p {\n        margin: 0;\n    }\n\n    @media (max-width: 767px) {\n        .lari-faq-loop {\n            grid-template-columns: repeat(1, minmax(0, 1fr));\n        }\n    }\n<\/style>\n\n<div class=\"lari-faq-block\">\n    <div class=\"lari-faq-loop faq-4856393\">\n            <div class=\"faq-left-items\">\n                        <div class=\"lari-faq-item\">\n                <div class=\"faq-title\">\n                    <h3>Qui puis-je contacter pour obtenir des conseils sur l&rsquo;int\u00e9grit\u00e9 de la recherche ?<\/h3>\n                    <span class=\"faq-icon\">\n                        <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n                <div class=\"faq-details\">\n                    Si vous avez des questions sur l'int\u00e9grit\u00e9 de la recherche et que vous \u00eates chercheur, \u00e9tudiant ou membre du personnel d'une organisation membre du LARI ou affili\u00e9 au syst\u00e8me de recherche publique du Luxembourg, n'h\u00e9sitez pas \u00e0 contacter le secr\u00e9taire g\u00e9n\u00e9ral du LARI par <a href=\"mailto:secretarygeneral@lari.lu\">courrier \u00e9lectronique<\/a>, par t\u00e9l\u00e9phone (+352 621 553 884), en utilisant le formulaire de contact de ce site web ou en vous rendant \u00e0 notre bureau de Belval (8, avenue des Hauts-Fourneaux, L-4362 Esch-sur-Alzette, 3e \u00e9tage).\nVous pouvez \u00e9galement prendre contact avec le secr\u00e9taire g\u00e9n\u00e9ral de l'Institut pour savoir si vous souhaitez d\u00e9poser une all\u00e9gation de manquement aux r\u00e8gles de la recherche.\nIl est toujours possible de demander des conseils sur la mani\u00e8re de g\u00e9rer une situation dans laquelle vous ne savez pas quoi faire et o\u00f9 vous pensez qu'une faute professionnelle a pu \u00eatre commise, sans pour autant d\u00e9poser une plainte officielle.\nN'oubliez pas qu'en tant que bureau de l'int\u00e9grit\u00e9 de la recherche, le LARI est bien plac\u00e9 pour r\u00e9pondre aux questions g\u00e9n\u00e9rales sur l'int\u00e9grit\u00e9 de la recherche et pour vous indiquer o\u00f9 trouver de plus amples informations sur des sujets cl\u00e9s de l'int\u00e9grit\u00e9 de la recherche.\nSi vous avez des questions tr\u00e8s sp\u00e9cifiques \u00e0 un domaine de recherche particulier (par exemple, des questions sur la m\u00e9thodologie), il se peut que nous ne soyons pas en mesure de vous donner des conseils tr\u00e8s concrets.\nDans ce cas, nous ferons toutefois de notre mieux pour vous aider \u00e0 identifier des points de contact plus appropri\u00e9s.                     <\/div>\n            <\/div>\n                        <div class=\"lari-faq-item\">\n                <div class=\"faq-title\">\n                    <h3>Qui enqu\u00eate sur les cas d&rsquo;all\u00e9gations de mauvaise conduite dans la recherche et comment l&rsquo;ind\u00e9pendance des enqu\u00eates est-elle assur\u00e9e ?<\/h3>\n                    <span class=\"faq-icon\">\n                        <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n                <div class=\"faq-details\">\n                    Les cas d'all\u00e9gations d'inconduite en mati\u00e8re de recherche sont examin\u00e9s par la Commission pour l'int\u00e9grit\u00e9 de la recherche (CRI).\nLa CRI est un comit\u00e9 ind\u00e9pendant au sein du LARI, compos\u00e9 d'experts internationaux renomm\u00e9s en mati\u00e8re d'int\u00e9grit\u00e9 de la recherche, issus de divers horizons disciplinaires et g\u00e9ographiques.\nLa CRI compte actuellement sept membres.\nTous les membres du CRI viennent de l'ext\u00e9rieur du Luxembourg et ne sont affili\u00e9s \u00e0 aucune organisation membre du LARI.\nLes enqu\u00eates sont men\u00e9es sans aucune interf\u00e9rence de la part des organisations membres du LARI, c'est-\u00e0-dire que le CRI proc\u00e8de en toute ind\u00e9pendance et ne re\u00e7oit aucune directive ou ordre.\nLes dossiers sont principalement instruits par deux membres de la CRI, appel\u00e9s premier et deuxi\u00e8me lecteurs.\nEn g\u00e9n\u00e9ral, les membres de la CRI les plus comp\u00e9tents dans un domaine donn\u00e9 sont d\u00e9sign\u00e9s comme premier et deuxi\u00e8me lecteurs.\nToutefois, toutes les d\u00e9cisions importantes sont prises par l'ensemble du comit\u00e9.\nVous trouverez de plus amples informations sur le fonctionnement de la CRI dans le <a href=\"https:\/\/lari.lu\/wp-content\/uploads\/2024\/08\/LARI-CRI-ROP-12-June-2024.pdf\">r\u00e8glement int\u00e9rieur de la Commission nationale pour l'int\u00e9grit\u00e9 de la recherche<\/a>.\nSi la conduite d'une enqu\u00eate approfondie pr\u00e9suppose une expertise dans un domaine qui n'est pas couvert par les membres de la CRI, celle-ci peut faire appel \u00e0 des experts externes qui sont soumis aux m\u00eames crit\u00e8res de s\u00e9lection et sont tenus aux m\u00eames r\u00e8gles de confidentialit\u00e9 que les membres de la CRI.                         <\/div>\n            <\/div>\n                        <div class=\"lari-faq-item\">\n                <div class=\"faq-title\">\n                    <h3>O\u00f9 puis-je trouver des lignes directrices sur l&rsquo;int\u00e9grit\u00e9 de la recherche, telles que des conseils sp\u00e9cifiques \u00e0 un domaine ou \u00e0 un sujet ?<\/h3>\n                    <span class=\"faq-icon\">\n                        <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n                <div class=\"faq-details\">\n                    Les liens ci-dessus vous dirigeront vers un grand nombre des plateformes les plus compl\u00e8tes sur l'int\u00e9grit\u00e9 de la recherche et les sujets connexes, tels que l'\u00e9thique de la recherche et la recherche et l'innovation responsables.\nL'une des listes les plus compl\u00e8tes et les plus faciles \u00e0 consulter de lignes directrices sur des sujets sp\u00e9cifiques (par exemple, la paternit\u00e9 d'une \u0153uvre) est disponible dans une <a href=\"https:\/\/embassy.science\/wiki\/Special:BrowseData\/Resource?_search_Resource_Type%5B0%5D=Guidelines\">section<\/a> d\u00e9di\u00e9e aux <a href=\"https:\/\/embassy.science\/wiki\/Special:BrowseData\/Resource?_search_Resource_Type%5B0%5D=Guidelines\">lignes directrices sur le site de l'Ambassade des bonnes pratiques scientifiques<\/a>.                 <\/div>\n            <\/div>\n                        <div class=\"lari-faq-item\">\n                <div class=\"faq-title\">\n                    <h3>LARI dispose-t-il d&rsquo;un comit\u00e9 d&rsquo;\u00e9thique de la recherche, d&rsquo;un comit\u00e9 d&rsquo;examen \u00e9thique ou d&rsquo;un comit\u00e9 d&rsquo;examen institutionnel ?<\/h3>\n                    <span class=\"faq-icon\">\n                        <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n                <div class=\"faq-details\">\n                    Non, LARI n'est pas un comit\u00e9 d'\u00e9thique de la recherche, un comit\u00e9 d'\u00e9valuation \u00e9thique ou un comit\u00e9 d'examen institutionnel.\nIl n'effectue donc pas d'\u00e9valuation \u00e9thique des recherches.\nVous trouverez de plus amples informations sur l'organisme responsable des \u00e9valuations \u00e9thiques au sein de votre organisation et pour la recherche que vous menez sur le site Web de votre institution.\nSi vous avez des difficult\u00e9s \u00e0 trouver les informations pertinentes, n'h\u00e9sitez pas \u00e0 nous contacter et nous ferons de notre mieux pour vous fournir les informations et les contacts que vous recherchez.\nBien que l'\u00e9thique de la recherche et l'int\u00e9grit\u00e9 de la recherche se recoupent sur le plan conceptuel, elles sont r\u00e9gies de mani\u00e8re quelque peu diff\u00e9rente.\nVous trouverez un aper\u00e7u utile de la relation entre l'\u00e9thique de la recherche et l'int\u00e9grit\u00e9 de la recherche, ainsi que du travail des comit\u00e9s d'\u00e9thique de la recherche et des bureaux d'int\u00e9grit\u00e9 de la recherche, dans le <a href=\"https:\/\/eneri.eu\/e-manual\/\">manuel de l'ENERI intitul\u00e9 Int\u00e9grit\u00e9 de la recherche et \u00e9thique.<\/a>                     <\/div>\n            <\/div>\n                        <div class=\"lari-faq-item\">\n                <div class=\"faq-title\">\n                    <h3>Qui peut signaler au LARI des cas de suspicion de mauvaise conduite en mati\u00e8re de recherche ?<\/h3>\n                    <span class=\"faq-icon\">\n                        <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n                <div class=\"faq-details\">\n                    Les all\u00e9gations d'inconduite en mati\u00e8re de recherche peuvent \u00eatre signal\u00e9es par toute personne ayant connaissance d'un cas d'inconduite en mati\u00e8re de recherche dans une organisation membre du LARI (Universit\u00e9 du Luxembourg, FNR, LIH, LISER, LIST) ou dans le cadre d'une recherche financ\u00e9e par le FNR, ou ayant des motifs raisonnables de soup\u00e7onner un tel cas.\nTous les rapports doivent \u00eatre faits de bonne foi.\nLARI prot\u00e8ge les auteurs de rapports (\"d\u00e9nonciateurs\") ainsi que tous les acteurs impliqu\u00e9s dans une enqu\u00eate (tels que les t\u00e9moins collaborateurs et la personne vis\u00e9e par les all\u00e9gations) conform\u00e9ment \u00e0 la loi et aux bonnes pratiques d\u00e9crites dans le <a href=\"https:\/\/zenodo.org\/records\/8192478\">manuel ENRIO sur la protection des d\u00e9nonciateurs dans le domaine de la recherche<\/a>.\nVous trouverez de plus amples informations sur la mani\u00e8re de signaler une all\u00e9gation ainsi que sur l'acc\u00e8s \u00e0 notre plateforme de signalement de cas dans la <a href=\"https:\/\/lari.lu\/investigation\/\">section Enqu\u00eates.<\/a>                   <\/div>\n            <\/div>\n                        <div class=\"lari-faq-item\">\n                <div class=\"faq-title\">\n                    <h3>LARI peut-il organiser un atelier, un s\u00e9minaire ou une s\u00e9ance de formation sur le th\u00e8me de l&rsquo;int\u00e9grit\u00e9 de la recherche \u00e0 l&rsquo;intention de notre organisation ?<\/h3>\n                    <span class=\"faq-icon\">\n                        <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n                <div class=\"faq-details\">\n                    Oui, cela fait partie de la mission du LARI de fournir une formation et un enseignement sur l'int\u00e9grit\u00e9 de la recherche aux organisations membres du LARI.\nCes ateliers, s\u00e9minaires et sessions de formation sont gratuits pour les organisations membres de LARI ainsi que pour les chercheurs, les \u00e9tudiants et le personnel qui leur sont affili\u00e9s.\nVeuillez contacter le secr\u00e9taire g\u00e9n\u00e9ral du LARI<a href=\"mailto:secretarygeneral@lari.lu\">(secretarygeneral@lari.lu)<\/a> si vous souhaitez obtenir de plus amples informations ou discuter plus en d\u00e9tail de ce que le LARI peut vous offrir.                  <\/div>\n            <\/div>\n                    <\/div>\n\n        <div class=\"faq-right-items\">\n                        <div class=\"lari-faq-item\">\n                <div class=\"faq-title\">\n                    <h3>Mon organisation peut-elle devenir membre de la LARI ?<\/h3>\n                    <span class=\"faq-icon\">\n                        <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n                <div class=\"faq-details\">\n                    Si votre organisation est bas\u00e9e au Luxembourg et qu'elle effectue ou finance des recherches, cela est potentiellement possible.\nLes statuts du LARI d\u00e9finissent la proc\u00e9dure \u00e0 suivre pour devenir une organisation membre du LARI.\nSi votre organisation souhaite devenir une organisation membre du LARI, veuillez contacter le secr\u00e9taire g\u00e9n\u00e9ral du LARI en lui communiquant les d\u00e9tails de votre demande<a href=\"mailto:secretarygeneral@lari.lu\">(secretarygeneral@lari.lu)<\/a>.                  <\/div>\n            <\/div>\n                        <div class=\"lari-faq-item\">\n                <div class=\"faq-title\">\n                    <h3>Les conclusions des enqu\u00eates de la Commission pour l&rsquo;int\u00e9grit\u00e9 de la recherche (CRI) peuvent-elles faire l&rsquo;objet d&rsquo;un recours ?<\/h3>\n                    <span class=\"faq-icon\">\n                        <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n                <div class=\"faq-details\">\n                    Non, la LARI n'\u00e9tant pas un tribunal ou un syst\u00e8me similaire, il n'existe pas non plus de proc\u00e9dure d'appel formelle.\nLes rapports finaux de la Commission pour l'int\u00e9grit\u00e9 de la recherche (CRI) sont bas\u00e9s sur la mani\u00e8re dont la CRI comprend les faits de l'affaire et comportent les \u00e9l\u00e9ments suivants :\n1) un r\u00e9sum\u00e9 des r\u00e9sultats de l'enqu\u00eate,\n2) une \u00e9valuation des r\u00e9sultats de l'enqu\u00eate, y compris une d\u00e9claration claire sur l'existence ou non d'une faute de recherche,\n3) une \u00e9valuation de la gravit\u00e9 de la faute de recherche si elle a eu lieu,\n4) des recommandations sur les mesures correctives, r\u00e9paratrices et\/ou pr\u00e9ventives \u00e0 l'intention des parties concern\u00e9es, et\n5) les enseignements tir\u00e9s de l'enqu\u00eate, notamment en ce qui concerne les mesures qui auraient pu emp\u00eacher l'inconduite en mati\u00e8re de recherche si elle s'\u00e9tait produite.\nEn d'autres termes, l'IRE \u00e9labore un avis fond\u00e9 sur des preuves et formule des recommandations sur mesure \u00e0 partir de ses conclusions factuelles, mais elle ne se prononce pas, au sens juridique du terme, sur une question ou n'applique pas de mesures.\nToutefois, la CRI peut rouvrir une enqu\u00eate si de nouveaux \u00e9l\u00e9ments de preuve substantiels sont apparus depuis l'ach\u00e8vement de l'enqu\u00eate initiale.                        <\/div>\n            <\/div>\n                        <div class=\"lari-faq-item\">\n                <div class=\"faq-title\">\n                    <h3>La LARI est-elle une organisation judiciaire ou un tribunal ?<\/h3>\n                    <span class=\"faq-icon\">\n                        <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n                <div class=\"faq-details\">\n                    Le LARI ne fait pas partie du syst\u00e8me judiciaire civil, p\u00e9nal ou administratif luxembourgeois.\nEn outre, LARI ne peut pas donner et ne donne pas de conseils juridiques.\nLARI est une organisation \u00e0 but non lucratif cr\u00e9\u00e9e par l'Universit\u00e9 du Luxembourg, le Fonds national de la recherche (FNR), l'Institut luxembourgeois de la sant\u00e9 (LIH), l'Institut luxembourgeois de recherche socio-\u00e9conomique (LISER) et l'Institut luxembourgeois des sciences et technologies (LIST) qui, par l'interm\u00e9diaire de sa Commission pour l'int\u00e9grit\u00e9 de la recherche (CRI), m\u00e8ne des enqu\u00eates ind\u00e9pendantes dans les cas d'all\u00e9gations d'inconduite en mati\u00e8re de recherche ou d'autres pratiques de recherche inacceptables telles que d\u00e9finies dans le <a href=\"https:\/\/allea.org\/portfolio-item\/european-code-of-conduct-2023\/\">Code de conduite europ\u00e9en pour l'int\u00e9grit\u00e9 de la recherche<\/a>.\nLes enqu\u00eates sont conclues par des rapports finaux qui recommandent des actions correctives, r\u00e9paratrices et pr\u00e9ventives aux institutions et acteurs impliqu\u00e9s dans un cas donn\u00e9 si une inconduite en mati\u00e8re de recherche ou d'autres pratiques de recherche inacceptables ont \u00e9t\u00e9 d\u00e9tect\u00e9es.\nLa responsabilit\u00e9 de la mise en \u0153uvre des recommandations incombe principalement aux organisations membres du LARI impliqu\u00e9es dans un cas donn\u00e9.\nNi le LARI en g\u00e9n\u00e9ral ni le CRI en particulier n'ont de pouvoirs d'ex\u00e9cution directs.\nCependant, le LARI se r\u00e9serve le droit de prendre des mesures pour garantir l'int\u00e9grit\u00e9 du dossier scientifique publi\u00e9 si les organisations membres et les autres acteurs impliqu\u00e9s dans un cas donn\u00e9 ne demandent pas les corrections, les r\u00e9tractations ou les mesures connexes n\u00e9cessaires pour restaurer l'int\u00e9grit\u00e9 du dossier scientifique dans un d\u00e9lai raisonnable apr\u00e8s la conclusion d'une enqu\u00eate.                      <\/div>\n            <\/div>\n                        <div class=\"lari-faq-item\">\n                <div class=\"faq-title\">\n                    <h3>Comment la LARI prot\u00e8ge-t-elle les rapporteurs\/plaignants (\u00ab\u00a0d\u00e9nonciateurs\u00a0\u00bb), les t\u00e9moins et les autres parties prenantes d&rsquo;une enqu\u00eate ?<\/h3>\n                    <span class=\"faq-icon\">\n                        <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n                <div class=\"faq-details\">\n                    En g\u00e9n\u00e9ral, la LARI suit les recommandations formul\u00e9es dans le<a href=\"https:\/\/zenodo.org\/records\/8192478\"> manuel ENRIO sur la protection des d\u00e9nonciateurs dans la recherche<\/a> et, bien s\u00fbr, toutes les exigences l\u00e9gales applicables, telles que celles li\u00e9es \u00e0 la protection des donn\u00e9es et de la vie priv\u00e9e.\nLe partage des donn\u00e9es entre les organisations membres du LARI et le LARI.\nPar exemple, le partage de donn\u00e9es entre les organisations membres de LARI et LARI est r\u00e9gi par un accord de partage de donn\u00e9es sp\u00e9cifique et les flux d'informations entre le FNR et LARI sont r\u00e9gis par un protocole d'accord adapt\u00e9 en raison du r\u00f4le unique du FNR en tant qu'organisme de financement de la recherche dans le syst\u00e8me de recherche luxembourgeois.\nUne mesure de protection typique consiste \u00e0 ne pas mentionner les noms des t\u00e9moins collaborateurs et des rapporteurs\/plaignants dans les communications avec les autres parties \u00e0 l'enqu\u00eate et dans les rapports finaux, \u00e0 moins que ces personnes ne consentent explicitement \u00e0 \u00eatre identifi\u00e9es par leur nom.\nCependant, en raison de la nature des conflits li\u00e9s \u00e0 l'int\u00e9grit\u00e9 de la recherche, le LARI ne peut pas garantir que les autres parties \u00e0 l'enqu\u00eate ne seront pas en mesure de d\u00e9duire l'identit\u00e9 des rapporteurs de cas\/plaignants et des t\u00e9moins, car souvent seul un nombre limit\u00e9 de personnes a connaissance de certaines situations, de certaines donn\u00e9es, de certains conflits, etc.\nDans les conflits de paternit\u00e9, par exemple, il n'y a g\u00e9n\u00e9ralement qu'un petit nombre de personnes impliqu\u00e9es.\nLorsqu'il s'agit de prot\u00e9ger les personnes impliqu\u00e9es dans une affaire contre des pressions ou des repr\u00e9sailles (qu'il s'agisse de rapporteurs\/plaignants, de t\u00e9moins ou de la personne vis\u00e9e par les all\u00e9gations), le LARI demande la protection n\u00e9cessaire \u00e0 l'organisation membre du LARI impliqu\u00e9e dans l'affaire et collabore \u00e9troitement avec les responsables institutionnels respectifs pour mettre en place des mesures de protection.\nLes personnes impliqu\u00e9es dans une affaire peuvent toujours contacter le LARI pour demander plus d'informations sur les mesures de protection mises en place.                       <\/div>\n            <\/div>\n                        <div class=\"lari-faq-item\">\n                <div class=\"faq-title\">\n                    <h3>Les enqu\u00eates sur les all\u00e9gations de mauvaise conduite dans la recherche sont-elles payantes ?<\/h3>\n                    <span class=\"faq-icon\">\n                        <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n                <div class=\"faq-details\">\n                    Non, il n'y a pas de frais.                <\/div>\n            <\/div>\n                        <div class=\"lari-faq-item\">\n                <div class=\"faq-title\">\n                    <h3>Combien de temps durent les enqu\u00eates sur les cas d&rsquo;all\u00e9gations de mauvaise conduite dans la recherche ?<\/h3>\n                    <span class=\"faq-icon\">\n                        <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                        <\/svg>\n                    <\/span>\n                <\/div>\n                <div class=\"faq-details\">\n                    En g\u00e9n\u00e9ral, la Commission pour l'int\u00e9grit\u00e9 de la recherche (CRI) de la LARI a pour objectif de mener \u00e0 bien une enqu\u00eate sur une all\u00e9gation d'inconduite en mati\u00e8re de recherche dans un d\u00e9lai de cinq mois \u00e0 compter de l'ouverture de l'enqu\u00eate, \u00e0 moins que des obligations l\u00e9gales ne l'exigent autrement (cela peut \u00eatre le cas pour des all\u00e9gations li\u00e9es au plagiat si elles sont signal\u00e9es par des canaux garantissant le respect de la l\u00e9gislation sur les d\u00e9nonciations).\nLe CRI a pour objectif de d\u00e9cider de l'ouverture d'une enqu\u00eate dans un d\u00e9lai maximum de 30 jours ouvrables \u00e0 compter de la r\u00e9ception de l'all\u00e9gation.\nEn g\u00e9n\u00e9ral, les d\u00e9cisions sont prises beaucoup plus rapidement.\nDans des cas exceptionnels (par exemple, en raison d'informations insuffisantes pour \u00e9valuer la cr\u00e9dibilit\u00e9 d'une all\u00e9gation ou d'informations insuffisantes pour d\u00e9terminer si une all\u00e9gation rel\u00e8ve des attributions et du champ d'application de la CRI), la d\u00e9cision peut prendre plus de temps.\nLes cas englobant des all\u00e9gations qui doivent faire l'objet d'une enqu\u00eate dans un d\u00e9lai fix\u00e9 par la loi, ainsi que les all\u00e9gations pour lesquelles aucune obligation l\u00e9gale ne s'applique, peuvent \u00eatre scind\u00e9s en deux enqu\u00eates.\nToutefois, l'exp\u00e9rience (du LARI et de nombreux autres bureaux d'int\u00e9grit\u00e9 de la recherche d'autres pays) a montr\u00e9 que certaines affaires sont tr\u00e8s complexes et n\u00e9cessitent l'analyse d'un grand nombre de preuves ou une consultation approfondie avec les parties prenantes de l'affaire.\nCes cas peuvent n\u00e9cessiter beaucoup plus de temps pour \u00eatre men\u00e9s \u00e0 bien.\nSi la dur\u00e9e d'une enqu\u00eate d\u00e9passe cinq mois ou un d\u00e9lai pertinent sp\u00e9cifi\u00e9 par la loi, le secr\u00e9taire g\u00e9n\u00e9ral du LARI informe mensuellement les parties prenantes de l'affaire de la mani\u00e8re sp\u00e9cifi\u00e9e \u00e0 l'article 9.8 du <a href=\"https:\/\/lari.lu\/wp-content\/uploads\/2024\/08\/LARI-CRI-ROP-12-June-2024.pdf\">r\u00e8glement int\u00e9rieur de la Commission nationale pour l'int\u00e9grit\u00e9 de la recherche<\/a>.         &nbsp;                <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n    <div class=\"lari-faq-not-found\">\n        <p>There is no more<\/p>\n    <\/div>\n    <div class=\"lari-faq-pag\">\n        <button class=\"lari-faq-load\" data-page=\"1\" data-per-page=\"12\">\n            Load more\n            <svg width=\"18\" height=\"19\" viewBox=\"0 0 18 19\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <circle cx=\"9\" cy=\"9.5\" r=\"8.5\" transform=\"rotate(-90 9 9.5)\" fill=\"white\" stroke=\"black\"\/>\n                <path d=\"M10 12.5L13 9.5M13 9.5L10 6.5M13 9.5H5\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n            <\/svg>\n        <\/button>\n    <\/div>\n<\/div>\n\n<script>\n    (function($) {\n        'use strict';\n\n        $(document).ready(function() {\n\n            $('.lari-faq-load').on('click', function(e) {\n                e.preventDefault();\n\n                let currentPage = $(this).attr('data-page');\n                let perPage = $(this).attr('data-per-page');\n\n                $('.faq-4856393').addClass('loading');\n                $.ajax({\n                    url: \"https:\/\/lari.lu\/wp-admin\/admin-ajax.php\",\n\t\t\t\t\ttype: 'POST',\n\t\t\t\t\tdataType: 'json',\n\t\t\t\t\tdata: {\n\t\t\t\t\t\taction: 'lari_faq_load_more',\n\t\t\t\t\t\tcurrentPage: currentPage,\n                        perPage: perPage,\n\t\t\t\t\t},\n                    success: function(data) {\n                        $('.lari-faq-load').attr('data-page', data.next_page);\n                        $('.faq-4856393').removeClass('loading');\n                        if(data.left_items.length != 0 && data.left_items.length != 0) {\n                            data.left_items.forEach((value) => {\n                                let leftItem = `<div class=\"lari-faq-item\">\n                                    <div class=\"faq-title\">\n                                        <h3>${value.title}<\/h3>\n                                        <span class=\"faq-icon\">\n                                            <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                                <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                            <\/svg>\n                                        <\/span>\n                                    <\/div>\n                                    <div class=\"faq-details\">\n                                        ${value.detail}\n                                    <\/div>\n                                <\/div>`;\n                                let newLeftItem = $(leftItem);\n                                $('.faq-left-items').append(newLeftItem);\n                            });\n\n                            data.right_items.forEach((value) => {\n                                let rightItem = `<div class=\"lari-faq-item\">\n                                    <div class=\"faq-title\">\n                                        <h3>${value.title}<\/h3>\n                                        <span class=\"faq-icon\">\n                                            <svg width=\"8\" height=\"4\" viewBox=\"0 0 8 4\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                                <path d=\"M7 3.5L4 0.5L1 3.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                                            <\/svg>\n                                        <\/span>\n                                    <\/div>\n                                    <div class=\"faq-details\">\n                                        ${value.detail}\n                                    <\/div>\n                                <\/div>`;\n                                let newrightItem = $(rightItem);\n                                $('.faq-right-items').append(newrightItem);\n                            });\n                        } else {\n                            $('.lari-faq-not-found').show().delay(1500).fadeOut();\n                        }\n                    },\n                    error: function(err) {\n                        console.log(err);\n                    }\n                });\n            });\n\n            $(document).on('click', '.faq-4856393 .lari-faq-item', function(e) {\n\t\t\t\te.preventDefault();\n\t\t\t\tlet item = $(this);\n\t\t\t\tlet details = item.find('.faq-details');\n                $('.faq-4856393 .lari-faq-item').not(item).css('z-index', -1);\n\n\t\t\t\titem.toggleClass('faq-show');\n\t\t\t\tdetails.slideToggle();\n\t\t\t});\n\n        });\n    })(jQuery);\n<\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ressources Sur cette page, vous trouverez un ensemble de ressources qui vous aideront \u00e0 mieux comprendre l&rsquo;int\u00e9grit\u00e9 de la recherche et la conduite responsable de la recherche en g\u00e9n\u00e9ral, et les activit\u00e9s de la LARI en particulier.L&rsquo;aper\u00e7u comprend des liens vers des codes de conduite, des lignes directrices et des recommandations sur la mani\u00e8re de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1313","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/lari.lu\/fr\/wp-json\/wp\/v2\/pages\/1313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lari.lu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lari.lu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lari.lu\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lari.lu\/fr\/wp-json\/wp\/v2\/comments?post=1313"}],"version-history":[{"count":7,"href":"https:\/\/lari.lu\/fr\/wp-json\/wp\/v2\/pages\/1313\/revisions"}],"predecessor-version":[{"id":2074,"href":"https:\/\/lari.lu\/fr\/wp-json\/wp\/v2\/pages\/1313\/revisions\/2074"}],"wp:attachment":[{"href":"https:\/\/lari.lu\/fr\/wp-json\/wp\/v2\/media?parent=1313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}