{"id":1327,"date":"2024-05-14T04:32:23","date_gmt":"2024-05-14T04:32:23","guid":{"rendered":"https:\/\/lari.themesawesome.com\/praevention\/"},"modified":"2025-05-07T07:22:38","modified_gmt":"2025-05-07T07:22:38","slug":"praevention","status":"publish","type":"page","link":"https:\/\/lari.lu\/de\/praevention\/","title":{"rendered":"Pr\u00e4vention"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1327\" class=\"elementor elementor-1327 elementor-556\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d95d7f e-con-full e-flex e-con e-parent\" data-id=\"5d95d7f\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-859b1b1 e-con-full hero-col-1 e-flex e-con e-child\" data-id=\"859b1b1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b90bb4 title-hero2 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7b90bb4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Pr\u00e4vention<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-701a863 e-con-full e-flex elementor-invisible e-con e-parent\" data-id=\"701a863\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-9beff7f e-con-full e-flex e-con e-child\" data-id=\"9beff7f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf0f34a elementor-widget elementor-widget-spacer\" data-id=\"bf0f34a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f6b9359 e-con-full e-flex e-con e-parent\" data-id=\"f6b9359\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7f1e401 e-con-full e-flex e-con e-child\" data-id=\"7f1e401\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9b6ffa2 elementor-widget-tablet__width-initial elementor-widget elementor-widget-lari-alt-link-loop\" data-id=\"9b6ffa2\" data-element_type=\"widget\" data-widget_type=\"lari-alt-link-loop.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\n.lari-alt-link-wrapper {\n    display: flex;\n    align-items: center;\n    column-gap: 4px;\n    row-gap: 10px;\n    flex-wrap: wrap;\n}\n\n.lari-alt-link-wrapper a {\n    color: unset;\n    line-height: 1.2;\n}\n\n.lari-alt-link-wrapper a span {\n    border-bottom: 1px;\n    border-bottom-style: solid;\n}\n\n@media only screen and (max-width: 768px) {\n\n    .lari-alt-link-wrapper a{\n        color: unset;\n        line-height: 1.2;\n    }\n}\n\n<\/style>\n\n<div class=\"lari-alt-link-wrapper\">\n    <span>\n        Die F\u00f6rderung einer Kultur der wissenschaftlichen Integrit\u00e4t in unseren Mitgliedsorganisationen sowie pr\u00e4ventive Ma\u00dfnahmen zur Verhinderung wissenschaftlichen Fehlverhaltens sind ein wichtiger Eckpfeiler unserer Aktivit\u00e4ten. Wir f\u00f6rdern wissenschaftliche Integrit\u00e4t und gute wissenschaftliche Praxis durch eine Vielzahl von Ma\u00dfnahmen, insbesondere durch Aus- und Weiterbildung, Beratung sowie Sensibilisierung und \u00d6ffentlichkeitsarbeit. Alle von uns angebotenen Dienstleistungen sind f\u00fcr LARI-Mitgliedsorganisationen und die an ihnen t\u00e4tigen Forschenden, Studierenden und sonstigen Mitarbeitenden kostenlos.\nWenn Sie weitere Informationen \u00fcber Trainings und andere Bildungsformate erhalten, an Veranstaltungen teilnehmen, Anliegen vorbringen oder zus\u00e4tzliche Informationen erhalten m\u00f6chten, k\u00f6nnen Sie uns gerne in unserem B\u00fcro in Belval (8, avenue des Hauts-Fourneaux, 3. Stock) besuchen oder unseren Generalsekretr\u00e4r        <a href=\"mailto:secretarygeneral@lari.lu\">\n            <span>kontaktieren<\/span>\n\n            <svg style=\"vertical-align: middle;\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <circle cx=\"8\" cy=\"8\" r=\"8\" transform=\"rotate(-90 8 8)\" fill=\"black\"\/>\n                <path d=\"M10.8285 9.41414L10.8285 5.1715M10.8285 5.1715L6.58583 5.1715M10.8285 5.1715L5.17161 10.8284\" stroke=\"white\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n            <\/svg>\n        <\/a>\n            <\/span>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cdee16 e-con-full e-flex e-con e-parent\" data-id=\"3cdee16\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0982b3f e-con-full e-flex e-con e-child\" data-id=\"0982b3f\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a8624ab e-con-full e-flex e-con e-child\" data-id=\"a8624ab\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5bf167 elementor-widget elementor-widget-lari-prevention-loop\" data-id=\"f5bf167\" data-element_type=\"widget\" data-widget_type=\"lari-prevention-loop.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\n\n.lari-prevention-wrapper{\n    padding: 0;\n}\n\n.lari-prevention-wrapper .prevention-content{\n    display: flex;\n    column-gap: 138px;\n}\n\n.lari-prevention-wrapper .prevention-content .img-prevention{\n    min-height: 250px;\n    min-width: 561px;\n    max-height: 250px;\n}\n\n.lari-prevention-wrapper .prevention-content .img-prevention img{\n    width: 100%;\n    max-height: 250px;\n    object-fit: cover;\n    border-radius: 10px;\n}\n\n.lari-prevention-wrapper .prevention-content .faq-prevention{\n    display: flex;\n    flex-direction: column;\n    gap: 20px;\n}\n\n.prevention-title-wrap {\n    display: flex;\n    align-items: flex-start;\n    column-gap: 96px;\n    margin-bottom: 40px;\n    position: relative;\n}\n.lari-prevention-wrapper .prevention-number {\n    font-size: 12px;\n    color: #D5433B;\n    margin: 0;\n    padding-top: 9px;\n}\n\n.lari-prevention-wrapper .prevention-number-mobile {\n    display: none;\n}\n\n.prevention-title{\n    display: flex;\n    flex-direction: column;\n}\n\n.prevention-title .title {\n    font-size: 32px;\n    line-height: 1.5;\n    margin-top: 0;\n    margin-bottom: 0;\n}\n.prevention-title .subtitle {\n    font-size: 16px;\n    line-height: 1;\n    margin: 0;\n}\n.faq-prevention-title {\n    display: flex;\n    align-items: center;\n    gap: 10px;\n    font-weight: 700;\n    cursor: pointer;\n}\n.lari-prevention-wrapper .faq-prevention-title span{\n\n}\n.faq-prevention-subtitle {\n    display: none;\n}\n.faq-prevention-subtitle span {\n    font-size: 16px;\n    line-height: 1.2;\n    color: #000000;\n    margin-top: 5px;\n    margin-bottom: 0;\n}\n.faq-prevention-subtitle span a {\n    display: inline-flex;\n    align-items: center;\n    gap: 5px;\n    color: inherit;\n    line-height: inherit;\n    text-decoration: underline;\n}\n.faq-prevention-item .faq-prevention-title svg {\n    transform: rotate(180deg);\n    -webkit-transform: rotate(180deg);\n    transition: all 0.3s ease;\n}   \n.faq-prevention-item.faq-show .faq-prevention-title svg {\n    transform: rotate(0deg);\n    -webkit-transform: rotate(0deg);\n}\n\n@media only screen and (max-width: 1440px){\n    .lari-prevention-wrapper .prevention-content .faq-prevention{\n        width: 448px;\n        max-width: 448px;\n    }\n}\n\n@media only screen and (max-width: 1024px) {\n    .lari-prevention-wrapper{\n        width: 80%;\n        margin: auto;\n    }\n    .lari-prevention-wrapper .prevention-number-mobile{\n        position: absolute;\n        top: 10px;\n        left: -70px;\n        display: block;\n        font-size: 12px;\n        color: #D5433B;\n    }\n    .lari-prevention-wrapper .prevention-title-wrap .prevention-number{\n        display: none;\n    }\n\n    .lari-prevention-wrapper .prevention-content .faq-prevention{\n        width: 100%;\n        max-width: 100%;\n    }\n\n    .lari-prevention-wrapper .prevention-content{\n        flex-direction: column;\n        row-gap: 40px;\n    }\n}\n\n@media only screen and (max-width: 767px) {\n    \n    .prevention-title-wrap{\n        flex-direction: column;\n    }\n\n    .lari-prevention-wrapper{\n        width: 100%;\n    }\n    \n    .lari-prevention-wrapper .prevention-number-mobile{\n        position: relative;\n        top: unset;\n        left: unset;\n        display: block;\n        font-size: 12px;\n        color: #D5433B;\n    }\n    .lari-prevention-wrapper .prevention-title-wrap .prevention-number{\n        display: none;\n    }\n    \n    .lari-prevention-wrapper .prevention-content{\n        flex-direction: column;\n        row-gap: 40px;\n    }\n}\n\n@media only screen and (max-width: 600px) {\n    \n    .lari-prevention-wrapper .prevention-content .img-prevention{\n        height: 250px;\n        min-height: 250px;\n        max-height: 250px;\n        width: 100%;\n        min-width: 100%;\n    }\n\n    .lari-prevention-wrapper .prevention-content .img-prevention img{\n        height: 250px;\n        min-height: 250px;\n        max-height: 250px;\n        width: 100%;\n        min-width: 100%;\n    }\n}\n<\/style>\n\n<div class=\"lari-prevention-wrapper\">\n    <div class=\"prevention-title-wrap\">\n        <span class=\"prevention-number-mobile\">\n            001        <\/span>\n        <p class=\"prevention-number\">\n            001        <\/p>\n        <div class=\"prevention-title\">\n            <h3 class=\"title\">\n                Trainings und Schulungen            <\/h3>\n            <h5 class=\"subtitle\">\n                f\u00fcr Forschende             <\/h5>\n        <\/div>\n    <\/div>\n\n    <div class=\"prevention-content\">\n        <div class=\"img-prevention\">\n            <img decoding=\"async\" src=\"https:\/\/lari.lu\/wp-content\/uploads\/2024\/08\/teaching.png\" alt=\"\">\n        <\/div>\n\n        <div class=\"faq-prevention faq-prevention-494652009\">\n                                                <div class=\"faq-prevention-item\">\n                        <div class=\"faq-prevention-title\">\n                            <span>Was sind die Lernziele der von LARI angebotenen Schulungen zur wissenschaftlichen Integrit\u00e4t?<\/span>\n                            <svg width=\"17\" height=\"17\" viewBox=\"0 0 17 17\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <circle opacity=\"0.3\" cx=\"8.5\" cy=\"8.5\" r=\"8\" transform=\"rotate(-180 8.5 8.5)\" fill=\"#529FDC\"\/>\n                                <path d=\"M11.5 9.5L8.5 6.5L5.5 9.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                            <\/svg>\n                        <\/div>\n\n                        <div class=\"faq-prevention-subtitle\">\n                            <span>\n                                Das \u00fcbergreifende Ziel unserer Schulungen ist es, Forschenden zu helfen, verantwortungsvoll mit  Herausforderungen mit Bezug zu wissenschaftlicher Integrit\u00e4t umzugehen. Die Lernziele der einzelnen Schulungen h\u00e4ngen von einer Vielzahl von Faktoren ab, z. B. dem Karrierestadium und dem disziplin\u00e4ren Hintergrund der Teilnehmenden, ihren Interessen sowie dem Zeitrahmen und dem Format der Schulung.\nZu den Themen, die wir in unseren Schulungen in der Regel behandeln, geh\u00f6ren u. a. die wichtigsten Grunds\u00e4tze und Werte wissenschaftlicher Integrit\u00e4t, die Beziehung zwischen wissenschaftlicher Integrit\u00e4t und Forschungsethik, die Publikationsethik (z. B. ethische Praktiken der Autorenschaft, verantwortungsvolle Peer-Reviews), die Bewertung von Forschung und Forschenden und ihre Auswirkungen auf Integrit\u00e4t in der Wissenschaft, verantwortungsvolle open Science (z. B. offener Zugang und offene Daten und ihre Grenzen) sowie verantwortungsvolle Btereuung des wissenschaftlichen Nachwuchses. Generell sind wir stets bem\u00fcht, die thematischen Schwerpunkte der Schulungen auf die Bed\u00fcrfnisse der Teilnehmenden abzustimmen. \nAlle von LARI angebotenen Schulungen basieren auf einem lernerzentrierten, aktiven Lernansatz. Daher beinhalten die Schulungen viele interaktive \u00dcbungen und haben einen starken Fokus auf die Entwicklung und Kultivierung von F\u00e4higkeiten und Gewohnheiten, die es Forschern erm\u00f6glichen, kompetent und verantwortungsbewusst mit den Herausforderungen der Integrit\u00e4t in der Forschung umzugehen.                            <\/span>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"faq-prevention-item\">\n                        <div class=\"faq-prevention-title\">\n                            <span>Auf welchen Leitf\u00e4den und Richtlinien basieren die Schulungen?<\/span>\n                            <svg width=\"17\" height=\"17\" viewBox=\"0 0 17 17\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <circle opacity=\"0.3\" cx=\"8.5\" cy=\"8.5\" r=\"8\" transform=\"rotate(-180 8.5 8.5)\" fill=\"#529FDC\"\/>\n                                <path d=\"M11.5 9.5L8.5 6.5L5.5 9.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                            <\/svg>\n                        <\/div>\n\n                        <div class=\"faq-prevention-subtitle\">\n                            <span>\n                                Das wichtigste Leitdokument f\u00fcr unsere Schulungen zur sowie f\u00fcr alle anderen Aktivit\u00e4ten der LARI ist der Europ\u00e4ische Verhaltenskodex f\u00fcr die Integrit\u00e4t der Forschung. Wir st\u00fctzen uns jedoch auch auf mehrere andere wichtige Leitf\u00e4den, die spezifischere Orientierung bieten als der Europ\u00e4ische Verhaltenskodex, der von seiner Konzeption her ein allgemeines Referenzdokument ist. Zu den anderen Leitf\u00e4den, die wir bei Schulungen h\u00e4ufig vorstellen und er\u00f6rtern, geh\u00f6ren beispielsweise die Vancouver-Empfehlungen zur Autorenschaft, die CRediT-Taxonomie zu den Rollen der Mitwirkenden, die Declaration on Research Assessment (DORA), der TRUST-Verhaltenskodex f\u00fcr gerechte Forschungspartnerschaften und die ROSiE-Leitlinien f\u00fcr verantwortungsvolle offene Wissenschaft. \nDar\u00fcber hinaus nutzen wir das Fachwissen aus Projekten wie VIRT2UE, Path2Integrity, INTEGRITY, ROSiE sowie Materialien der Embassy of Good Science und ENAI.                            <\/span>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"faq-prevention-item\">\n                        <div class=\"faq-prevention-title\">\n                            <span>Welches Format haben die Schulungen?<\/span>\n                            <svg width=\"17\" height=\"17\" viewBox=\"0 0 17 17\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <circle opacity=\"0.3\" cx=\"8.5\" cy=\"8.5\" r=\"8\" transform=\"rotate(-180 8.5 8.5)\" fill=\"#529FDC\"\/>\n                                <path d=\"M11.5 9.5L8.5 6.5L5.5 9.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                            <\/svg>\n                        <\/div>\n\n                        <div class=\"faq-prevention-subtitle\">\n                            <span>\n                                Je nach Bedarf und Verf\u00fcgbarkeit der Teilnehmenden werden Schulungen entweder pers\u00f6nlich\/vor Ort, vollst\u00e4ndig online oder in einem hybriden Format angeboten, das sowohl Online- als auch Pr\u00e4senz-Elemente umfasst. F\u00fcr Gruppen mit mehr als 12 Teilnehmenden bevorzugen wir ein Pr\u00e4senz- oder gemischtes Format, um eine sinnvolle Interaktion und Gruppen\u00fcbungen zu erm\u00f6glichen. \nDie Schulungen werden f\u00fcr Gruppen von 5 bis 20 Teilnehmenden angeboten. Je nach den angestrebten Lernzielen k\u00f6nnen die Teilnehmenden einen \u00e4hnlichen oder unterschiedlichen fachlichen Hintergrund sowie \u00e4hnliche oder unterschiedliche Karrierestufen aufweisen.                             <\/span>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"faq-prevention-item\">\n                        <div class=\"faq-prevention-title\">\n                            <span>Was kosten die Schulungen?<\/span>\n                            <svg width=\"17\" height=\"17\" viewBox=\"0 0 17 17\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <circle opacity=\"0.3\" cx=\"8.5\" cy=\"8.5\" r=\"8\" transform=\"rotate(-180 8.5 8.5)\" fill=\"#529FDC\"\/>\n                                <path d=\"M11.5 9.5L8.5 6.5L5.5 9.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                            <\/svg>\n                        <\/div>\n\n                        <div class=\"faq-prevention-subtitle\">\n                            <span>\n                                Die Schulungen sind kostenlos f\u00fcr Forschende, Studierende und Mitarbeitende von LARI-Mitgliedsorganisationen (Universit\u00e4t Luxemburg, FNR, LIH, LISER, LIST).                            <\/span>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"faq-prevention-item\">\n                        <div class=\"faq-prevention-title\">\n                            <span>Wie kann ich mein Interesse an einer Schulung bekunden und\/oder mich f\u00fcr eine Schulung anmelden?<\/span>\n                            <svg width=\"17\" height=\"17\" viewBox=\"0 0 17 17\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <circle opacity=\"0.3\" cx=\"8.5\" cy=\"8.5\" r=\"8\" transform=\"rotate(-180 8.5 8.5)\" fill=\"#529FDC\"\/>\n                                <path d=\"M11.5 9.5L8.5 6.5L5.5 9.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                            <\/svg>\n                        <\/div>\n\n                        <div class=\"faq-prevention-subtitle\">\n                            <span>\n                                Die Schulungen werden auf Anfrage angeboten. Wenn Sie sich \u00fcber Schulungsm\u00f6glichkeiten erkundigen oder eine Schulung buchen m\u00f6chten, wenden Sie sich bitte an den LARI-Generalsekret\u00e4r per E-Mail an secretarygeneral@lari.lu oder besuchen Sie uns in unserem B\u00fcro in Belval. \nLARI bietet regelm\u00e4\u00dfig Schulungen f\u00fcr Doktoranden in Zusammenarbeit mit der Abteilung Transferable Skills der Universit\u00e4t Luxemburg an.                            <\/span>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n    <\/div>\n<\/div>\n\n<script>\n    (function($) {\n        'use strict';\n\n        $(document).ready(function() {\n            $('.faq-prevention-494652009 .faq-prevention-item').on('click', function(e) {\n                e.preventDefault();\n\n                let item = $(this);\n\t\t\t\tlet details = item.find('.faq-prevention-subtitle');\n\n\t\t\t\titem.toggleClass('faq-show');\n\t\t\t\tdetails.slideToggle();\n            });\n        });\n    })(jQuery);\n<\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b18d3b e-con-full e-flex e-con e-child\" data-id=\"7b18d3b\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1e0c682 e-con-full e-flex e-con e-child\" data-id=\"1e0c682\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f9accb elementor-widget elementor-widget-lari-prevention-loop\" data-id=\"3f9accb\" data-element_type=\"widget\" data-widget_type=\"lari-prevention-loop.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\n\n.lari-prevention-wrapper{\n    padding: 0;\n}\n\n.lari-prevention-wrapper .prevention-content{\n    display: flex;\n    column-gap: 138px;\n}\n\n.lari-prevention-wrapper .prevention-content .img-prevention{\n    min-height: 250px;\n    min-width: 561px;\n    max-height: 250px;\n}\n\n.lari-prevention-wrapper .prevention-content .img-prevention img{\n    width: 100%;\n    max-height: 250px;\n    object-fit: cover;\n    border-radius: 10px;\n}\n\n.lari-prevention-wrapper .prevention-content .faq-prevention{\n    display: flex;\n    flex-direction: column;\n    gap: 20px;\n}\n\n.prevention-title-wrap {\n    display: flex;\n    align-items: flex-start;\n    column-gap: 96px;\n    margin-bottom: 40px;\n    position: relative;\n}\n.lari-prevention-wrapper .prevention-number {\n    font-size: 12px;\n    color: #D5433B;\n    margin: 0;\n    padding-top: 9px;\n}\n\n.lari-prevention-wrapper .prevention-number-mobile {\n    display: none;\n}\n\n.prevention-title{\n    display: flex;\n    flex-direction: column;\n}\n\n.prevention-title .title {\n    font-size: 32px;\n    line-height: 1.5;\n    margin-top: 0;\n    margin-bottom: 0;\n}\n.prevention-title .subtitle {\n    font-size: 16px;\n    line-height: 1;\n    margin: 0;\n}\n.faq-prevention-title {\n    display: flex;\n    align-items: center;\n    gap: 10px;\n    font-weight: 700;\n    cursor: pointer;\n}\n.lari-prevention-wrapper .faq-prevention-title span{\n\n}\n.faq-prevention-subtitle {\n    display: none;\n}\n.faq-prevention-subtitle span {\n    font-size: 16px;\n    line-height: 1.2;\n    color: #000000;\n    margin-top: 5px;\n    margin-bottom: 0;\n}\n.faq-prevention-subtitle span a {\n    display: inline-flex;\n    align-items: center;\n    gap: 5px;\n    color: inherit;\n    line-height: inherit;\n    text-decoration: underline;\n}\n.faq-prevention-item .faq-prevention-title svg {\n    transform: rotate(180deg);\n    -webkit-transform: rotate(180deg);\n    transition: all 0.3s ease;\n}   \n.faq-prevention-item.faq-show .faq-prevention-title svg {\n    transform: rotate(0deg);\n    -webkit-transform: rotate(0deg);\n}\n\n@media only screen and (max-width: 1440px){\n    .lari-prevention-wrapper .prevention-content .faq-prevention{\n        width: 448px;\n        max-width: 448px;\n    }\n}\n\n@media only screen and (max-width: 1024px) {\n    .lari-prevention-wrapper{\n        width: 80%;\n        margin: auto;\n    }\n    .lari-prevention-wrapper .prevention-number-mobile{\n        position: absolute;\n        top: 10px;\n        left: -70px;\n        display: block;\n        font-size: 12px;\n        color: #D5433B;\n    }\n    .lari-prevention-wrapper .prevention-title-wrap .prevention-number{\n        display: none;\n    }\n\n    .lari-prevention-wrapper .prevention-content .faq-prevention{\n        width: 100%;\n        max-width: 100%;\n    }\n\n    .lari-prevention-wrapper .prevention-content{\n        flex-direction: column;\n        row-gap: 40px;\n    }\n}\n\n@media only screen and (max-width: 767px) {\n    \n    .prevention-title-wrap{\n        flex-direction: column;\n    }\n\n    .lari-prevention-wrapper{\n        width: 100%;\n    }\n    \n    .lari-prevention-wrapper .prevention-number-mobile{\n        position: relative;\n        top: unset;\n        left: unset;\n        display: block;\n        font-size: 12px;\n        color: #D5433B;\n    }\n    .lari-prevention-wrapper .prevention-title-wrap .prevention-number{\n        display: none;\n    }\n    \n    .lari-prevention-wrapper .prevention-content{\n        flex-direction: column;\n        row-gap: 40px;\n    }\n}\n\n@media only screen and (max-width: 600px) {\n    \n    .lari-prevention-wrapper .prevention-content .img-prevention{\n        height: 250px;\n        min-height: 250px;\n        max-height: 250px;\n        width: 100%;\n        min-width: 100%;\n    }\n\n    .lari-prevention-wrapper .prevention-content .img-prevention img{\n        height: 250px;\n        min-height: 250px;\n        max-height: 250px;\n        width: 100%;\n        min-width: 100%;\n    }\n}\n<\/style>\n\n<div class=\"lari-prevention-wrapper\">\n    <div class=\"prevention-title-wrap\">\n        <span class=\"prevention-number-mobile\">\n            002        <\/span>\n        <p class=\"prevention-number\">\n            002        <\/p>\n        <div class=\"prevention-title\">\n            <h3 class=\"title\">\n                Beratung &amp; Information            <\/h3>\n            <h5 class=\"subtitle\">\n                zur Themen wissenschaftlicher Integrit\u00e4t            <\/h5>\n        <\/div>\n    <\/div>\n\n    <div class=\"prevention-content\">\n        <div class=\"img-prevention\">\n            <img decoding=\"async\" src=\"https:\/\/lari.lu\/wp-content\/uploads\/2024\/05\/advice-and-guidance.png\" alt=\"\">\n        <\/div>\n\n        <div class=\"faq-prevention faq-prevention-292125846\">\n                                                <div class=\"faq-prevention-item\">\n                        <div class=\"faq-prevention-title\">\n                            <span>Wer kann sich an die LARI wenden und um Rat und Hilfe bitten?<\/span>\n                            <svg width=\"17\" height=\"17\" viewBox=\"0 0 17 17\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <circle opacity=\"0.3\" cx=\"8.5\" cy=\"8.5\" r=\"8\" transform=\"rotate(-180 8.5 8.5)\" fill=\"#529FDC\"\/>\n                                <path d=\"M11.5 9.5L8.5 6.5L5.5 9.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                            <\/svg>\n                        <\/div>\n\n                        <div class=\"faq-prevention-subtitle\">\n                            <span>\n                                Alle LARI-Dienstleistungen stehen den LARI-Mitgliedsorganisationen (Universit\u00e4t Luxemburg, FNR, LIH, LISER, LIST) sowie den an ihnen t\u00e4tigen Forschenden, Studierenden und anderen Mitarbeitenden kostenlos zur Verf\u00fcgung. Mitglieder der luxemburgischen \u00d6ffentlichkeit, die sich f\u00fcr wissenschaftliche Integrit\u00e4t interessieren, k\u00f6nnen sich ebenfalls an LARI wenden, wenn sie mehr \u00fcber das Thema erfahren m\u00f6chten.                             <\/span>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"faq-prevention-item\">\n                        <div class=\"faq-prevention-title\">\n                            <span>Wie kann ich mich an die LARI wenden, um Rat und Hilfe zu erhalten?<\/span>\n                            <svg width=\"17\" height=\"17\" viewBox=\"0 0 17 17\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <circle opacity=\"0.3\" cx=\"8.5\" cy=\"8.5\" r=\"8\" transform=\"rotate(-180 8.5 8.5)\" fill=\"#529FDC\"\/>\n                                <path d=\"M11.5 9.5L8.5 6.5L5.5 9.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                            <\/svg>\n                        <\/div>\n\n                        <div class=\"faq-prevention-subtitle\">\n                            <span>\n                                Sie k\u00f6nnen sich mit uns in Verbindung setzen, indem Sie eine E-Mail an unseren Generalsekret\u00e4r (secretarygeneral@lari.lu) schreiben, das Kontaktformular auf dieser Website ausf\u00fcllen, uns anrufen (+352 621 553 884) oder uns in unserem B\u00fcro in Belval besuchen.                             <\/span>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"faq-prevention-item\">\n                        <div class=\"faq-prevention-title\">\n                            <span>Welche Art von Beratung bietet die LARI an?<\/span>\n                            <svg width=\"17\" height=\"17\" viewBox=\"0 0 17 17\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <circle opacity=\"0.3\" cx=\"8.5\" cy=\"8.5\" r=\"8\" transform=\"rotate(-180 8.5 8.5)\" fill=\"#529FDC\"\/>\n                                <path d=\"M11.5 9.5L8.5 6.5L5.5 9.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                            <\/svg>\n                        <\/div>\n\n                        <div class=\"faq-prevention-subtitle\">\n                            <span>\n                                Unsere Beratungst\u00e4tigkeit orientiert sich am Europ\u00e4ischen Verhaltenskodex f\u00fcr die Integrit\u00e4t der Forschung.  Themen, zu denen wir Ratschl\u00e4ge und Hilfestellungen geben k\u00f6nnen, sind unter anderem Fragen zur Autorenschaft, zu verantwortungsvoller Open Science, zu verantwortungsvollem Peer-Review und zu angemessener Betreuung des wissenschaftlichen Nachwuchses. \nWir keine Beratung zu Themen anbieten, die nicht unmittelbar mit wissenschaftlicher Integrit\u00e4t zusammenh\u00e4ngen zusammenh\u00e4ngen, wie z. B. Bel\u00e4stigung, Arbeitsrecht und andere rechtliche Fragen, da sie nicht in unseren satzungsgem\u00e4\u00dfen Zust\u00e4ndigkeitsbereich fallen und wir \u00fcberdies nicht \u00fcber die erforderliche einschl\u00e4gige Expertise verf\u00fcgen. Wir versuchen jedoch, Personen mit Fragen zu solchen Themen an die richtigen Anlaufstellen f\u00fcr ihre Anliegen zu verweisen.\nDar\u00fcber hinaus ist es wichtig zu betonen, dass LARI keine Ethikkommission ist. Zwar gibt es \u00dcberschneidungen zwischen Forschungsethik (ethics ad scientia) und wissenschaftlicher Integrit\u00e4t (ethics in scientia), doch bieten wir in der Regel keine Beratung zu Fragen an, die vollst\u00e4ndig in den Bereich der Forschungsethik fallen.                              <\/span>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n    <\/div>\n<\/div>\n\n<script>\n    (function($) {\n        'use strict';\n\n        $(document).ready(function() {\n            $('.faq-prevention-292125846 .faq-prevention-item').on('click', function(e) {\n                e.preventDefault();\n\n                let item = $(this);\n\t\t\t\tlet details = item.find('.faq-prevention-subtitle');\n\n\t\t\t\titem.toggleClass('faq-show');\n\t\t\t\tdetails.slideToggle();\n            });\n        });\n    })(jQuery);\n<\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3188b20 e-con-full e-flex e-con e-child\" data-id=\"3188b20\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a66532a e-con-full e-flex e-con e-child\" data-id=\"a66532a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1960f51 elementor-widget elementor-widget-lari-prevention-loop\" data-id=\"1960f51\" data-element_type=\"widget\" data-widget_type=\"lari-prevention-loop.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\n\n.lari-prevention-wrapper{\n    padding: 0;\n}\n\n.lari-prevention-wrapper .prevention-content{\n    display: flex;\n    column-gap: 138px;\n}\n\n.lari-prevention-wrapper .prevention-content .img-prevention{\n    min-height: 250px;\n    min-width: 561px;\n    max-height: 250px;\n}\n\n.lari-prevention-wrapper .prevention-content .img-prevention img{\n    width: 100%;\n    max-height: 250px;\n    object-fit: cover;\n    border-radius: 10px;\n}\n\n.lari-prevention-wrapper .prevention-content .faq-prevention{\n    display: flex;\n    flex-direction: column;\n    gap: 20px;\n}\n\n.prevention-title-wrap {\n    display: flex;\n    align-items: flex-start;\n    column-gap: 96px;\n    margin-bottom: 40px;\n    position: relative;\n}\n.lari-prevention-wrapper .prevention-number {\n    font-size: 12px;\n    color: #D5433B;\n    margin: 0;\n    padding-top: 9px;\n}\n\n.lari-prevention-wrapper .prevention-number-mobile {\n    display: none;\n}\n\n.prevention-title{\n    display: flex;\n    flex-direction: column;\n}\n\n.prevention-title .title {\n    font-size: 32px;\n    line-height: 1.5;\n    margin-top: 0;\n    margin-bottom: 0;\n}\n.prevention-title .subtitle {\n    font-size: 16px;\n    line-height: 1;\n    margin: 0;\n}\n.faq-prevention-title {\n    display: flex;\n    align-items: center;\n    gap: 10px;\n    font-weight: 700;\n    cursor: pointer;\n}\n.lari-prevention-wrapper .faq-prevention-title span{\n\n}\n.faq-prevention-subtitle {\n    display: none;\n}\n.faq-prevention-subtitle span {\n    font-size: 16px;\n    line-height: 1.2;\n    color: #000000;\n    margin-top: 5px;\n    margin-bottom: 0;\n}\n.faq-prevention-subtitle span a {\n    display: inline-flex;\n    align-items: center;\n    gap: 5px;\n    color: inherit;\n    line-height: inherit;\n    text-decoration: underline;\n}\n.faq-prevention-item .faq-prevention-title svg {\n    transform: rotate(180deg);\n    -webkit-transform: rotate(180deg);\n    transition: all 0.3s ease;\n}   \n.faq-prevention-item.faq-show .faq-prevention-title svg {\n    transform: rotate(0deg);\n    -webkit-transform: rotate(0deg);\n}\n\n@media only screen and (max-width: 1440px){\n    .lari-prevention-wrapper .prevention-content .faq-prevention{\n        width: 448px;\n        max-width: 448px;\n    }\n}\n\n@media only screen and (max-width: 1024px) {\n    .lari-prevention-wrapper{\n        width: 80%;\n        margin: auto;\n    }\n    .lari-prevention-wrapper .prevention-number-mobile{\n        position: absolute;\n        top: 10px;\n        left: -70px;\n        display: block;\n        font-size: 12px;\n        color: #D5433B;\n    }\n    .lari-prevention-wrapper .prevention-title-wrap .prevention-number{\n        display: none;\n    }\n\n    .lari-prevention-wrapper .prevention-content .faq-prevention{\n        width: 100%;\n        max-width: 100%;\n    }\n\n    .lari-prevention-wrapper .prevention-content{\n        flex-direction: column;\n        row-gap: 40px;\n    }\n}\n\n@media only screen and (max-width: 767px) {\n    \n    .prevention-title-wrap{\n        flex-direction: column;\n    }\n\n    .lari-prevention-wrapper{\n        width: 100%;\n    }\n    \n    .lari-prevention-wrapper .prevention-number-mobile{\n        position: relative;\n        top: unset;\n        left: unset;\n        display: block;\n        font-size: 12px;\n        color: #D5433B;\n    }\n    .lari-prevention-wrapper .prevention-title-wrap .prevention-number{\n        display: none;\n    }\n    \n    .lari-prevention-wrapper .prevention-content{\n        flex-direction: column;\n        row-gap: 40px;\n    }\n}\n\n@media only screen and (max-width: 600px) {\n    \n    .lari-prevention-wrapper .prevention-content .img-prevention{\n        height: 250px;\n        min-height: 250px;\n        max-height: 250px;\n        width: 100%;\n        min-width: 100%;\n    }\n\n    .lari-prevention-wrapper .prevention-content .img-prevention img{\n        height: 250px;\n        min-height: 250px;\n        max-height: 250px;\n        width: 100%;\n        min-width: 100%;\n    }\n}\n<\/style>\n\n<div class=\"lari-prevention-wrapper\">\n    <div class=\"prevention-title-wrap\">\n        <span class=\"prevention-number-mobile\">\n            003        <\/span>\n        <p class=\"prevention-number\">\n            003        <\/p>\n        <div class=\"prevention-title\">\n            <h3 class=\"title\">\n                Veranstaltungen und \u00d6ffentlichkeitsarbeit            <\/h3>\n            <h5 class=\"subtitle\">\n                zu Themen wissenschaftlicher Integrit\u00e4t            <\/h5>\n        <\/div>\n    <\/div>\n\n    <div class=\"prevention-content\">\n        <div class=\"img-prevention\">\n            <img decoding=\"async\" src=\"https:\/\/lari.lu\/wp-content\/uploads\/2024\/05\/awareness-raising.png\" alt=\"\">\n        <\/div>\n\n        <div class=\"faq-prevention faq-prevention-865590272\">\n                                                <div class=\"faq-prevention-item\">\n                        <div class=\"faq-prevention-title\">\n                            <span>Wann findet die n\u00e4chste Veranstaltung in Luxemburg oder der Gro\u00dfregion statt?<\/span>\n                            <svg width=\"17\" height=\"17\" viewBox=\"0 0 17 17\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <circle opacity=\"0.3\" cx=\"8.5\" cy=\"8.5\" r=\"8\" transform=\"rotate(-180 8.5 8.5)\" fill=\"#529FDC\"\/>\n                                <path d=\"M11.5 9.5L8.5 6.5L5.5 9.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                            <\/svg>\n                        <\/div>\n\n                        <div class=\"faq-prevention-subtitle\">\n                            <span>\n                                Anstehende Veranstaltungen werden im News-Bereich angek\u00fcndigt. Sie k\u00f6nnen uns auch in den sozialen Medien folgen, um \u00fcber kommende Veranstaltungen informiert zu werden.                            <\/span>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"faq-prevention-item\">\n                        <div class=\"faq-prevention-title\">\n                            <span>Wo kann ich mehr \u00fcber kommende Veranstaltungen erfahren?<\/span>\n                            <svg width=\"17\" height=\"17\" viewBox=\"0 0 17 17\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                                <circle opacity=\"0.3\" cx=\"8.5\" cy=\"8.5\" r=\"8\" transform=\"rotate(-180 8.5 8.5)\" fill=\"#529FDC\"\/>\n                                <path d=\"M11.5 9.5L8.5 6.5L5.5 9.5\" stroke=\"#529FDC\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n                            <\/svg>\n                        <\/div>\n\n                        <div class=\"faq-prevention-subtitle\">\n                            <span>\n                                Weitere Informationen \u00fcber bevorstehende Veranstaltungen finden Sie im Abschnitt Nachrichten. Wenn Sie die gesuchten Informationen nicht finden k\u00f6nnen, wenden Sie sich bitte an den Generalsekret\u00e4r der LARI per E-Mail an secretarygeneral@lari.lu oder \u00fcber die Kontaktseite auf dieser Website.                            <\/span>\n                        <\/div>\n                    <\/div>\n                                    <\/div>\n    <\/div>\n<\/div>\n\n<script>\n    (function($) {\n        'use strict';\n\n        $(document).ready(function() {\n            $('.faq-prevention-865590272 .faq-prevention-item').on('click', function(e) {\n                e.preventDefault();\n\n                let item = $(this);\n\t\t\t\tlet details = item.find('.faq-prevention-subtitle');\n\n\t\t\t\titem.toggleClass('faq-show');\n\t\t\t\tdetails.slideToggle();\n            });\n        });\n    })(jQuery);\n<\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7254a3 e-con-full e-flex e-con e-parent\" data-id=\"b7254a3\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-fb06ab4 e-con-full e-flex e-con e-child\" data-id=\"fb06ab4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db720f2 elementor-widget__width-auto elementor-align-left elementor-widget elementor-widget-button\" data-id=\"db720f2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:secretarygeneral@lari.lu\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"19\" viewBox=\"0 0 18 19\" fill=\"none\"><circle cx=\"9\" cy=\"9.5\" r=\"8.5\" transform=\"rotate(-90 9 9.5)\" fill=\"white\" stroke=\"black\"><\/circle><path d=\"M10 12.5L13 9.5M13 9.5L10 6.5M13 9.5H5\" stroke=\"black\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontakt aufnehmen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pr\u00e4vention Kontakt aufnehmen<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1327","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/lari.lu\/de\/wp-json\/wp\/v2\/pages\/1327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lari.lu\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lari.lu\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lari.lu\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lari.lu\/de\/wp-json\/wp\/v2\/comments?post=1327"}],"version-history":[{"count":28,"href":"https:\/\/lari.lu\/de\/wp-json\/wp\/v2\/pages\/1327\/revisions"}],"predecessor-version":[{"id":1923,"href":"https:\/\/lari.lu\/de\/wp-json\/wp\/v2\/pages\/1327\/revisions\/1923"}],"wp:attachment":[{"href":"https:\/\/lari.lu\/de\/wp-json\/wp\/v2\/media?parent=1327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}